{"id":2906,"date":"2018-02-27T16:33:06","date_gmt":"2018-02-27T15:33:06","guid":{"rendered":"https:\/\/www.tradimalt.com\/diventa-rivenditore\/"},"modified":"2022-03-23T16:53:46","modified_gmt":"2022-03-23T15:53:46","slug":"diventa-rivenditore","status":"publish","type":"page","link":"https:\/\/www.tradimalt.com\/en\/diventa-rivenditore\/","title":{"rendered":"Become a reseller"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2896,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-rivenditori.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-2906","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Become a reseller - Tradimalt<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tradimalt.com\/en\/diventa-rivenditore\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Become a reseller - Tradimalt\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tradimalt.com\/en\/diventa-rivenditore\/\" \/>\n<meta property=\"og:site_name\" content=\"Tradimalt\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TradimaltSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-23T15:53:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tradimalt.com\/wp-content\/uploads\/2018\/03\/header_trova-rivenditore_1920x350.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/diventa-rivenditore\\\/\",\"url\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/diventa-rivenditore\\\/\",\"name\":\"Become a reseller - Tradimalt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/diventa-rivenditore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/diventa-rivenditore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tradimalt.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/header_trova-rivenditore_1920x350.jpg\",\"datePublished\":\"2018-02-27T15:33:06+00:00\",\"dateModified\":\"2022-03-23T15:53:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/diventa-rivenditore\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/diventa-rivenditore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/diventa-rivenditore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tradimalt.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/header_trova-rivenditore_1920x350.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tradimalt.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/header_trova-rivenditore_1920x350.jpg\",\"width\":1920,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/diventa-rivenditore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/?lang=en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Become a reseller\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/\",\"name\":\"Tradimalt\",\"description\":\"Intonaco isolante malte intonaci edilizia premiscelati cementizi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/#organization\",\"name\":\"Tradimalt\",\"url\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tradimalt.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/cropped-tradimalt-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.tradimalt.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/cropped-tradimalt-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Tradimalt\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tradimalt.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TradimaltSpa\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/tradimalt\",\"https:\\\/\\\/it.pinterest.com\\\/tradimaltspa\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/tradimalt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Become a reseller - Tradimalt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tradimalt.com\/en\/diventa-rivenditore\/","og_locale":"en_US","og_type":"article","og_title":"Become a reseller - Tradimalt","og_url":"https:\/\/www.tradimalt.com\/en\/diventa-rivenditore\/","og_site_name":"Tradimalt","article_publisher":"https:\/\/www.facebook.com\/TradimaltSpa","article_modified_time":"2022-03-23T15:53:46+00:00","og_image":[{"width":1920,"height":350,"url":"https:\/\/www.tradimalt.com\/wp-content\/uploads\/2018\/03\/header_trova-rivenditore_1920x350.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tradimalt.com\/en\/diventa-rivenditore\/","url":"https:\/\/www.tradimalt.com\/en\/diventa-rivenditore\/","name":"Become a reseller - Tradimalt","isPartOf":{"@id":"https:\/\/www.tradimalt.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tradimalt.com\/en\/diventa-rivenditore\/#primaryimage"},"image":{"@id":"https:\/\/www.tradimalt.com\/en\/diventa-rivenditore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tradimalt.com\/wp-content\/uploads\/2018\/03\/header_trova-rivenditore_1920x350.jpg","datePublished":"2018-02-27T15:33:06+00:00","dateModified":"2022-03-23T15:53:46+00:00","breadcrumb":{"@id":"https:\/\/www.tradimalt.com\/en\/diventa-rivenditore\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tradimalt.com\/en\/diventa-rivenditore\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tradimalt.com\/en\/diventa-rivenditore\/#primaryimage","url":"https:\/\/www.tradimalt.com\/wp-content\/uploads\/2018\/03\/header_trova-rivenditore_1920x350.jpg","contentUrl":"https:\/\/www.tradimalt.com\/wp-content\/uploads\/2018\/03\/header_trova-rivenditore_1920x350.jpg","width":1920,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/www.tradimalt.com\/en\/diventa-rivenditore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tradimalt.com\/en\/?lang=en"},{"@type":"ListItem","position":2,"name":"Become a reseller"}]},{"@type":"WebSite","@id":"https:\/\/www.tradimalt.com\/en\/#website","url":"https:\/\/www.tradimalt.com\/en\/","name":"Tradimalt","description":"Intonaco isolante malte intonaci edilizia premiscelati cementizi","publisher":{"@id":"https:\/\/www.tradimalt.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tradimalt.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.tradimalt.com\/en\/#organization","name":"Tradimalt","url":"https:\/\/www.tradimalt.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tradimalt.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.tradimalt.com\/wp-content\/uploads\/2020\/09\/cropped-tradimalt-favicon.png","contentUrl":"https:\/\/www.tradimalt.com\/wp-content\/uploads\/2020\/09\/cropped-tradimalt-favicon.png","width":512,"height":512,"caption":"Tradimalt"},"image":{"@id":"https:\/\/www.tradimalt.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TradimaltSpa","http:\/\/www.linkedin.com\/company\/tradimalt","https:\/\/it.pinterest.com\/tradimaltspa\/","http:\/\/www.youtube.com\/user\/tradimalt"]}]}},"_links":{"self":[{"href":"https:\/\/www.tradimalt.com\/en\/wp-json\/wp\/v2\/pages\/2906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tradimalt.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tradimalt.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tradimalt.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tradimalt.com\/en\/wp-json\/wp\/v2\/comments?post=2906"}],"version-history":[{"count":1,"href":"https:\/\/www.tradimalt.com\/en\/wp-json\/wp\/v2\/pages\/2906\/revisions"}],"predecessor-version":[{"id":2907,"href":"https:\/\/www.tradimalt.com\/en\/wp-json\/wp\/v2\/pages\/2906\/revisions\/2907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tradimalt.com\/en\/wp-json\/wp\/v2\/media\/2896"}],"wp:attachment":[{"href":"https:\/\/www.tradimalt.com\/en\/wp-json\/wp\/v2\/media?parent=2906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}